{"id":69322,"date":"2023-02-24T16:15:10","date_gmt":"2023-02-24T15:15:10","guid":{"rendered":"https:\/\/www.depureco.com\/servizi\/"},"modified":"2023-03-27T15:46:49","modified_gmt":"2023-03-27T13:46:49","slug":"servicii","status":"publish","type":"page","link":"https:\/\/www.depureco.com\/ro\/servicii\/","title":{"rendered":"Servicii"},"content":{"rendered":"\n\t<div class=\"_canva-wp-block   _has-classes\">\n\n\t\t\n\t<div class=\"_header\">\n\n\t\t<div class=\"_header-icon hero-primary\">\n\t\t\t<div class=\"_header-icon-wrap canva-p-1\" style=\"background: var(--color-wp-block-bg-icon);\">\n\t\t\t\t<svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 256 256\" style=\"enable-background:new 0 0 256 256;\" xml:space=\"preserve\" class=\"_icon icon-wp-block-hero-primary \">\n<style type=\"text\/css\">\n\t.st0{fill:#1E88E5;}\n\t.st1{fill:#FF0000;}\n\t.st2{fill:none;stroke:#000000;stroke-width:6;stroke-linecap:round;stroke-linejoin:round;stroke-miterlimit:10;}\n\t.st3{fill:none;stroke:#000000;stroke-width:6;stroke-miterlimit:10;}\n\t.st4{fill:none;stroke:#000000;stroke-width:12;stroke-miterlimit:10;}\n\t.st5{display:none;}\n\t.st6{display:inline;fill:#E6007E;}\n<\/style>\n<g id=\"Livello_1\" focusable=\"false\">\n\t<rect x=\"52.4\" y=\"92.8\" width=\"97.6\" height=\"12\"><\/rect>\n\t<rect x=\"52.4\" y=\"121.4\" width=\"60\" height=\"6\"><\/rect>\n\t<path d=\"M84.4,188l-4.2-4.2l43-43c5.9-5.9,15.4-5.9,21.2,0c3.5,3.5,9.2,3.5,12.8,0l23.5-23.5c5.9-5.9,15.4-5.9,21.2,0l24.8,24.8\n\t\tl-4.2,4.2l-24.8-24.8c-3.5-3.5-9.2-3.5-12.8,0L161.4,145c-5.9,5.9-15.4,5.9-21.2,0c-3.5-3.5-9.2-3.5-12.8,0L84.4,188z\"><\/path>\n\t<g>\n\t\t<path d=\"M220,77.4v104H36v-104H220 M220,65.4H36c-6.6,0-12,5.4-12,12v104c0,6.6,5.4,12,12,12h184c6.6,0,12-5.4,12-12v-104\n\t\t\tC232,70.8,226.6,65.4,220,65.4L220,65.4z\"><\/path>\n\t<\/g>\n<\/g>\n<g id=\"Note_e_spacer\" class=\"st5\">\n\t<rect class=\"st6\" width=\"24\" height=\"24\"><\/rect>\n<\/g>\n<\/svg>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t<div class=\"_header-info canva-flex-1\">\n\t\t\t<span class=\"_title canva-block canva-fs-xsmall canva-lh-12 canva-fw-700\" style=\"color:var(--color-wp-block-title);\">\n\t\t\t\tHero\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"_description canva-block canva-fs-xxsmall canva-lh-11 canva-fw-400\" style=\"color:var(--color-wp-block-subtitle);\">\n\t\t\t\t\tHero con titoli, descrizioni, pulsanti, sfondi con immagini e video\t\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"_css_classes canva-block canva-fs-xxsmall canva-lh-11 canva-fw-400\" style=\"color:var(--color-wp-block-subtitle);\">\n\t\t\t\t\tCSS Classes: isdark\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\n\t\t<div class=\"_content canva-p-4\">\n\n\t\t\t\n\t\t\t\t<div class=\"_hero-preview canva-flex\">\n\n\t\t\t\t\t<figure id=\"media-73752\" class=\"canva-width-48 canva-p-0 canva-m-0 canva-mr-4\"  data-url=\"https:\/\/i0.wp.com\/www.depureco.com\/wp-content\/uploads\/2023\/03\/tre_aspiratori_copia_3.jpeg?fit=2400%2C952&#038;ssl=1\"  data-size=\"2400x952\"  width=\"640\" height=\"254\"><img decoding=\"auto\" class=\"_no-translate \"  src=\"https:\/\/i0.wp.com\/www.depureco.com\/wp-content\/uploads\/2023\/03\/tre_aspiratori_copia_3.jpeg?fit=640%2C254&#038;ssl=1\" loading=\"lazy\" alt=\"Olympus Digital Camera\" title=\"Olympus Digital Camera\" style=\"\" width=\"640\" height=\"254\"  fetchpriority=\"low\" \/> <figcaption class=\"image-caption block hidden\">Olympus Digital Camera<\/figcaption><\/figure>\n\t\t\t\t\t<div class=\"canva-info canva-flex-1 canva-ml-4\">\n\n\t\t\t\t\t\t<span class=\"canva-block canva-mb-2 canva-fs-h2 canva-font-theme canva-fw-700 canva-lh-11\">\n\t\t\t\t\t\t\tServicii\t\t\t\t\t\t<\/span>\n\n\t\t\t\t\t\t<span class=\"canva-block canva-fs-h4 canva-font-theme canva-lh-11\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\n\t\t\t\t\t\t<span class=\"canva-block canva-fs-h4 canva-font-theme canva-lh-11\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t<\/div>\n\n\n\n\n\t<div class=\"_canva-wp-block   _has-classes\" style=\"border: 1px dashed #1e88e5;\">\n\n\t\t\n\t<div class=\"_header\">\n\n\t\t<div class=\"_header-icon main-section-inner-blocks\">\n\t\t\t<div class=\"_header-icon-wrap canva-p-1\" style=\"background: var(--color-wp-block-bg-icon);\">\n\t\t\t\t<svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 256 256\" style=\"enable-background:new 0 0 256 256;\" xml:space=\"preserve\" class=\"_icon icon-wp-block-main-section-inner-blocks \">\n<style type=\"text\/css\">\n\t.st1{fill:#FF0000;}\n\t.st2{fill:none;stroke:#000000;stroke-width:6;stroke-linecap:round;stroke-linejoin:round;stroke-miterlimit:10;}\n\t.st3{fill:none;stroke:#000000;stroke-width:6;stroke-miterlimit:10;}\n\t.st4{fill:none;stroke:#000000;stroke-width:12;stroke-miterlimit:10;}\n\t.st5{display:none;}\n\t.st6{display:inline;fill:#E6007E;}\n<\/style>\n<g id=\"Livello_1\" focusable=\"false\">\n\t<g>\n\t\t<rect x=\"60.5\" y=\"181.4\" style=\"fill:#1e88e5;\" width=\"20\" height=\"12\"><\/rect>\n\t\t<rect x=\"88.5\" y=\"65.4\" style=\"fill:#1e88e5;\" width=\"20\" height=\"12\"><\/rect>\n\t\t<rect x=\"57.5\" y=\"65.4\" style=\"fill:#1e88e5;\" width=\"20\" height=\"12\"><\/rect>\n\t\t<rect x=\"91.5\" y=\"181.4\" style=\"fill:#1e88e5;\" width=\"20\" height=\"12\"><\/rect>\n\t\t<rect x=\"24.5\" y=\"133.4\" style=\"fill:#1e88e5;\" width=\"12\" height=\"20\"><\/rect>\n\t\t<rect x=\"24.5\" y=\"102.4\" style=\"fill:#1e88e5;\" width=\"12\" height=\"20\"><\/rect>\n\t\t<path style=\"fill:#1e88e5;\" d=\"M36.5,77.4h10v-12h-10c-6.6,0-12,5.4-12,12v0c0,6.4,0,14,0,14h12V77.4z\"><\/path>\n\t\t<path style=\"fill:#1e88e5;\" d=\"M212.5,65.4v12h8v16h12V74c0-4.7-3.8-8.6-8.6-8.6H212.5z\"><\/path>\n\t\t<path style=\"fill:#1e88e5;\" d=\"M36.5,164.4h-12v17c0,6.6,5.4,12,12,12h13v-12h-13V164.4z\"><\/path>\n\t\t<rect x=\"119.5\" y=\"65.4\" style=\"fill:#1e88e5;\" width=\"20\" height=\"12\"><\/rect>\n\t\t<rect x=\"181.5\" y=\"65.4\" style=\"fill:#1e88e5;\" width=\"20\" height=\"12\"><\/rect>\n\t\t<rect x=\"220.5\" y=\"135.4\" style=\"fill:#1e88e5;\" width=\"12\" height=\"20\"><\/rect>\n\t\t<path style=\"fill:#1e88e5;\" d=\"M220.5,181.4h-9v12h12.4c4.7,0,8.6-3.8,8.6-8.6v0v-3.4v-15h-12V181.4z\"><\/path>\n\t\t<rect x=\"220.5\" y=\"104.4\" style=\"fill:#1e88e5;\" width=\"12\" height=\"20\"><\/rect>\n\t\t<rect x=\"122.5\" y=\"181.4\" style=\"fill:#1e88e5;\" width=\"20\" height=\"12\"><\/rect>\n\t\t<rect x=\"184.5\" y=\"181.4\" style=\"fill:#1e88e5;\" width=\"16\" height=\"12\"><\/rect>\n\t\t<rect x=\"150.5\" y=\"65.4\" style=\"fill:#1e88e5;\" width=\"20\" height=\"12\"><\/rect>\n\t\t<rect x=\"153.5\" y=\"181.4\" style=\"fill:#1e88e5;\" width=\"20\" height=\"12\"><\/rect>\n\t<\/g>\n\t<path d=\"M52.5,53.7V36h151v17.7h12V36c0-6.6-5.4-12-12-12h-151c-6.6,0-12,5.4-12,12v17.7H52.5z\"><\/path>\n\t<path d=\"M203.5,202.3V220h-151v-17.7h-12V220c0,6.6,5.4,12,12,12h151c6.6,0,12-5.4,12-12v-17.7H203.5z\"><\/path>\n<\/g>\n<g id=\"Note_e_spacer\" class=\"st5\">\n\t<rect class=\"st6\" width=\"24\" height=\"24\"><\/rect>\n\t<rect y=\"232\" class=\"st6\" width=\"24\" height=\"24\"><\/rect>\n<\/g>\n<\/svg>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t<div class=\"_header-info canva-flex-1\">\n\t\t\t<span class=\"_title canva-block canva-fs-xsmall canva-lh-12 canva-fw-700\" style=\"color:var(--color-wp-block-title);\">\n\t\t\t\tSezione Main\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"_description canva-block canva-fs-xxsmall canva-lh-11 canva-fw-400\" style=\"color:var(--color-wp-block-subtitle);\">\n\t\t\t\t\tContenitore di blocchi per sezione di pagina\t\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"_css_classes canva-block canva-fs-xxsmall canva-lh-11 canva-fw-400\" style=\"color:var(--color-wp-block-subtitle);\">\n\t\t\t\t\tCSS Classes: bg-black isdark py-24\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n        \n\t\t<div class=\"_content canva-p-4 canva-bg-white\">\n\n\t\t\t\n\t\t\t<div class=\"user-locked-inner-blocks\">\n\t\t\t\t\n\n<div class=\"wp-block-columns\">\n<div class=\"wp-block-column col-span-12 _tos tos-slide-r\">\n<h4 class=\"fs-h1 lh-11 wp-block-heading\">Solicita\u021bI o<br><span class=\"text-selected\">Demonstra\u021bie<\/span><\/h4>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns _gap-default items-center\">\n<div class=\"wp-block-column col-span-12 md:col-span-2 md:col-start-2 _tos tos-slide-u\"><figure id=\"media-69323\" class=\"wp-editor w-40\"   data-url=\"https:\/\/www.depureco.com\/wp-content\/uploads\/2023\/03\/icon-depureco-dimostrazione.svg\" data-size=\"x\" ><img decoding=\"auto\" class=\"_no-translate \" loading=\"lazy\" src=\"https:\/\/www.depureco.com\/wp-content\/uploads\/2023\/03\/icon-depureco-dimostrazione.svg\" srcset=\"https:\/\/www.depureco.com\/wp-content\/uploads\/2023\/03\/icon-depureco-dimostrazione.svg 640w, https:\/\/www.depureco.com\/wp-content\/uploads\/2023\/03\/icon-depureco-dimostrazione.svg 1280w, \" sizes=\"(max-width: 640px) 640px, 100vw\" alt=\"Icon Depureco Dimostrazione\" title=\"Icon Depureco Dimostrazione\" style=\"\" width=\"100%\" height=\"100%\"  fetchpriority=\"low\" \/> <figcaption class=\"image-caption block hidden\">Icon Depureco Dimostrazione<\/figcaption><\/figure><\/div>\n\n\n\n<div class=\"wp-block-column col-span-12 md:col-span-8 md:col-start-5 _tos tos-slide-u\">\n<p>\u00cenainte de a cump\u0103ra este important s\u0103 verifica\u021bi func\u021bionarea aspiratoarelor profesionale Depureco \u0219i s\u0103 cunoa\u0219te\u021bi specifica\u021biile tehnice ale acestora. \u00cen acest scop pute\u021bi solicita o demonstra\u021bie de c\u0103tre echipa noastr\u0103 de tehnicieni specializa\u021bi \u0219i ne pute\u021bi vizita \u00een showroom, pentru a descoperi \u0219i testa \u00eentreaga gam\u0103 de produse, de la aspiratoarele monofazate \u0219i cele trifazate p\u00e2n\u0103 la separatoarele solid-lichid.<\/p>\n\n\n\n<p>Exper\u021bii no\u0219tri v\u0103 vor recomanda produsul cel mai adecvat pentru aspirarea materialelor lichide, solide sau nisipoase \u0219i v\u0103 vor oferi instruc\u021biunile necesare privind utilizarea corect\u0103 a aspiratoarelor industriale pe care le-a\u021bi ales.<\/p>\n\n\n\n\t<div class=\"_canva-wp-block\">\n\t\t\n\t<div class=\"_header\">\n\n\t\t<div class=\"_header-icon action-link\">\n\t\t\t<div class=\"_header-icon-wrap canva-p-1\" style=\"background: var(--color-wp-block-bg-icon);\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\" class=\"_icon link w-16\"><path d=\"M314.222 197.78c51.091 51.091 54.377 132.287 9.75 187.16-6.242 7.73-2.784 3.865-84.94 86.02-54.696 54.696-143.266 54.745-197.99 0-54.711-54.69-54.734-143.255 0-197.99 32.773-32.773 51.835-51.899 63.409-63.457 7.463-7.452 20.331-2.354 20.486 8.192a173.31 173.31 0 0 0 4.746 37.828c.966 4.029-.272 8.269-3.202 11.198L80.632 312.57c-32.755 32.775-32.887 85.892 0 118.8 32.775 32.755 85.892 32.887 118.8 0l75.19-75.2c32.718-32.725 32.777-86.013 0-118.79a83.722 83.722 0 0 0-22.814-16.229c-4.623-2.233-7.182-7.25-6.561-12.346 1.356-11.122 6.296-21.885 14.815-30.405l4.375-4.375c3.625-3.626 9.177-4.594 13.76-2.294 12.999 6.524 25.187 15.211 36.025 26.049zM470.958 41.04c-54.724-54.745-143.294-54.696-197.99 0-82.156 82.156-78.698 78.29-84.94 86.02-44.627 54.873-41.341 136.069 9.75 187.16 10.838 10.838 23.026 19.525 36.025 26.049 4.582 2.3 10.134 1.331 13.76-2.294l4.375-4.375c8.52-8.519 13.459-19.283 14.815-30.405.621-5.096-1.938-10.113-6.561-12.346a83.706 83.706 0 0 1-22.814-16.229c-32.777-32.777-32.718-86.065 0-118.79l75.19-75.2c32.908-32.887 86.025-32.755 118.8 0 32.887 32.908 32.755 86.025 0 118.8l-45.848 45.84c-2.93 2.929-4.168 7.169-3.202 11.198a173.31 173.31 0 0 1 4.746 37.828c.155 10.546 13.023 15.644 20.486 8.192 11.574-11.558 30.636-30.684 63.409-63.457 54.733-54.735 54.71-143.3-.001-197.991z\"><\/path><\/svg>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t<div class=\"_header-info canva-flex-1\">\n\t\t\t<span class=\"_title canva-block canva-fs-xsmall canva-lh-12 canva-fw-700\" style=\"color:var(--color-wp-block-title);\">\n\t\t\t\tAction Link\/Pulsante\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"_description canva-block canva-fs-xxsmall canva-lh-11 canva-fw-400\" style=\"color:var(--color-wp-block-subtitle);\">\n\t\t\t\t\tCrea un link\/pulsante tracciato come evento su GA\t\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"_css_classes canva-block canva-fs-xxsmall canva-lh-11 canva-fw-400\" style=\"color:var(--color-wp-block-subtitle);\">\n\t\t\t\t\tCSS Classes: mt-6\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\n\t\t<div class=\"_content canva-p-4\">\n\t\t\t\t\t\t\t<span class=\"canva-block canva-font-theme canva-fs-xsmall canva-lh-12\">\n\t\t\t\t\t<em>Fai click qui e poi sull&#8217;icona matita in alto per impostare il pulsante<\/em>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\n\t<\/div>\n\n\t<\/div>\n<\/div>\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n\n\n\n\t<div class=\"_canva-wp-block   _has-classes\" style=\"border: 1px dashed #1e88e5;\">\n\n\t\t\n\t<div class=\"_header\">\n\n\t\t<div class=\"_header-icon main-section-inner-blocks\">\n\t\t\t<div class=\"_header-icon-wrap canva-p-1\" style=\"background: var(--color-wp-block-bg-icon);\">\n\t\t\t\t<svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 256 256\" style=\"enable-background:new 0 0 256 256;\" xml:space=\"preserve\" class=\"_icon icon-wp-block-main-section-inner-blocks \">\n<style type=\"text\/css\">\n\t.st1{fill:#FF0000;}\n\t.st2{fill:none;stroke:#000000;stroke-width:6;stroke-linecap:round;stroke-linejoin:round;stroke-miterlimit:10;}\n\t.st3{fill:none;stroke:#000000;stroke-width:6;stroke-miterlimit:10;}\n\t.st4{fill:none;stroke:#000000;stroke-width:12;stroke-miterlimit:10;}\n\t.st5{display:none;}\n\t.st6{display:inline;fill:#E6007E;}\n<\/style>\n<g id=\"Livello_1\" focusable=\"false\">\n\t<g>\n\t\t<rect x=\"60.5\" y=\"181.4\" style=\"fill:#1e88e5;\" width=\"20\" height=\"12\"><\/rect>\n\t\t<rect x=\"88.5\" y=\"65.4\" style=\"fill:#1e88e5;\" width=\"20\" height=\"12\"><\/rect>\n\t\t<rect x=\"57.5\" y=\"65.4\" style=\"fill:#1e88e5;\" width=\"20\" height=\"12\"><\/rect>\n\t\t<rect x=\"91.5\" y=\"181.4\" style=\"fill:#1e88e5;\" width=\"20\" height=\"12\"><\/rect>\n\t\t<rect x=\"24.5\" y=\"133.4\" style=\"fill:#1e88e5;\" width=\"12\" height=\"20\"><\/rect>\n\t\t<rect x=\"24.5\" y=\"102.4\" style=\"fill:#1e88e5;\" width=\"12\" height=\"20\"><\/rect>\n\t\t<path style=\"fill:#1e88e5;\" d=\"M36.5,77.4h10v-12h-10c-6.6,0-12,5.4-12,12v0c0,6.4,0,14,0,14h12V77.4z\"><\/path>\n\t\t<path style=\"fill:#1e88e5;\" d=\"M212.5,65.4v12h8v16h12V74c0-4.7-3.8-8.6-8.6-8.6H212.5z\"><\/path>\n\t\t<path style=\"fill:#1e88e5;\" d=\"M36.5,164.4h-12v17c0,6.6,5.4,12,12,12h13v-12h-13V164.4z\"><\/path>\n\t\t<rect x=\"119.5\" y=\"65.4\" style=\"fill:#1e88e5;\" width=\"20\" height=\"12\"><\/rect>\n\t\t<rect x=\"181.5\" y=\"65.4\" style=\"fill:#1e88e5;\" width=\"20\" height=\"12\"><\/rect>\n\t\t<rect x=\"220.5\" y=\"135.4\" style=\"fill:#1e88e5;\" width=\"12\" height=\"20\"><\/rect>\n\t\t<path style=\"fill:#1e88e5;\" d=\"M220.5,181.4h-9v12h12.4c4.7,0,8.6-3.8,8.6-8.6v0v-3.4v-15h-12V181.4z\"><\/path>\n\t\t<rect x=\"220.5\" y=\"104.4\" style=\"fill:#1e88e5;\" width=\"12\" height=\"20\"><\/rect>\n\t\t<rect x=\"122.5\" y=\"181.4\" style=\"fill:#1e88e5;\" width=\"20\" height=\"12\"><\/rect>\n\t\t<rect x=\"184.5\" y=\"181.4\" style=\"fill:#1e88e5;\" width=\"16\" height=\"12\"><\/rect>\n\t\t<rect x=\"150.5\" y=\"65.4\" style=\"fill:#1e88e5;\" width=\"20\" height=\"12\"><\/rect>\n\t\t<rect x=\"153.5\" y=\"181.4\" style=\"fill:#1e88e5;\" width=\"20\" height=\"12\"><\/rect>\n\t<\/g>\n\t<path d=\"M52.5,53.7V36h151v17.7h12V36c0-6.6-5.4-12-12-12h-151c-6.6,0-12,5.4-12,12v17.7H52.5z\"><\/path>\n\t<path d=\"M203.5,202.3V220h-151v-17.7h-12V220c0,6.6,5.4,12,12,12h151c6.6,0,12-5.4,12-12v-17.7H203.5z\"><\/path>\n<\/g>\n<g id=\"Note_e_spacer\" class=\"st5\">\n\t<rect class=\"st6\" width=\"24\" height=\"24\"><\/rect>\n\t<rect y=\"232\" class=\"st6\" width=\"24\" height=\"24\"><\/rect>\n<\/g>\n<\/svg>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t<div class=\"_header-info canva-flex-1\">\n\t\t\t<span class=\"_title canva-block canva-fs-xsmall canva-lh-12 canva-fw-700\" style=\"color:var(--color-wp-block-title);\">\n\t\t\t\tSezione Main\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"_description canva-block canva-fs-xxsmall canva-lh-11 canva-fw-400\" style=\"color:var(--color-wp-block-subtitle);\">\n\t\t\t\t\tContenitore di blocchi per sezione di pagina\t\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"_css_classes canva-block canva-fs-xxsmall canva-lh-11 canva-fw-400\" style=\"color:var(--color-wp-block-subtitle);\">\n\t\t\t\t\tCSS Classes: bg-accent isdark py-24\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n        \n\t\t<div class=\"_content canva-p-4 canva-bg-white\">\n\n\t\t\t\n\t\t\t<div class=\"user-locked-inner-blocks\">\n\t\t\t\t\n\n<div class=\"wp-block-columns\">\n<div class=\"wp-block-column col-span-12 _tos tos-slide-r\">\n<h4 class=\"has-text-align-right fs-h1 lh-11 _tos tos-slide-r wp-block-heading\">Beneficia\u021bI de<br><span class=\"text-selected\">Asisten\u021b\u0103<\/span><\/h4>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns _gap-default items-center\">\n<div class=\"wp-block-column col-span-12 md:col-span-8 order-2 md:order-1 _tos tos-slide-u\">\n<p>Persoanele care aleg s\u0103 ni se adreseze \u0219i s\u0103 achizi\u021bioneze un aspirator industrial Depureco sunt con\u0219tiente de faptul c\u0103 suntem mai mult dec\u00e2t un furnizor: suntem parteneri al\u0103turi de dumneavoastr\u0103 \u00een fiecare etap\u0103 a procesului de v\u00e2nzare. chiar \u0219i dup\u0103 achizi\u021bionare. Pentru noi este important s\u0103 v\u0103 oferim asisten\u021b\u0103 \u0219i suport dedicat \u0219i rapid \u00een vederea solu\u021bion\u0103rii problemelor, pentru a v\u0103 garanta permanent func\u021bionarea optim\u0103 a aspiratoarelor industriale \u0219i a tuturor produselor Depureco. Printr-un serviciu la fa\u021ba locului \u0219i telefonic oferit de tehnicienii no\u0219tri specializa\u021bi.<\/p>\n\n\n\n\t<div class=\"_canva-wp-block\">\n\t\t\n\t<div class=\"_header\">\n\n\t\t<div class=\"_header-icon action-link\">\n\t\t\t<div class=\"_header-icon-wrap canva-p-1\" style=\"background: var(--color-wp-block-bg-icon);\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\" class=\"_icon link w-16\"><path d=\"M314.222 197.78c51.091 51.091 54.377 132.287 9.75 187.16-6.242 7.73-2.784 3.865-84.94 86.02-54.696 54.696-143.266 54.745-197.99 0-54.711-54.69-54.734-143.255 0-197.99 32.773-32.773 51.835-51.899 63.409-63.457 7.463-7.452 20.331-2.354 20.486 8.192a173.31 173.31 0 0 0 4.746 37.828c.966 4.029-.272 8.269-3.202 11.198L80.632 312.57c-32.755 32.775-32.887 85.892 0 118.8 32.775 32.755 85.892 32.887 118.8 0l75.19-75.2c32.718-32.725 32.777-86.013 0-118.79a83.722 83.722 0 0 0-22.814-16.229c-4.623-2.233-7.182-7.25-6.561-12.346 1.356-11.122 6.296-21.885 14.815-30.405l4.375-4.375c3.625-3.626 9.177-4.594 13.76-2.294 12.999 6.524 25.187 15.211 36.025 26.049zM470.958 41.04c-54.724-54.745-143.294-54.696-197.99 0-82.156 82.156-78.698 78.29-84.94 86.02-44.627 54.873-41.341 136.069 9.75 187.16 10.838 10.838 23.026 19.525 36.025 26.049 4.582 2.3 10.134 1.331 13.76-2.294l4.375-4.375c8.52-8.519 13.459-19.283 14.815-30.405.621-5.096-1.938-10.113-6.561-12.346a83.706 83.706 0 0 1-22.814-16.229c-32.777-32.777-32.718-86.065 0-118.79l75.19-75.2c32.908-32.887 86.025-32.755 118.8 0 32.887 32.908 32.755 86.025 0 118.8l-45.848 45.84c-2.93 2.929-4.168 7.169-3.202 11.198a173.31 173.31 0 0 1 4.746 37.828c.155 10.546 13.023 15.644 20.486 8.192 11.574-11.558 30.636-30.684 63.409-63.457 54.733-54.735 54.71-143.3-.001-197.991z\"><\/path><\/svg>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t<div class=\"_header-info canva-flex-1\">\n\t\t\t<span class=\"_title canva-block canva-fs-xsmall canva-lh-12 canva-fw-700\" style=\"color:var(--color-wp-block-title);\">\n\t\t\t\tAction Link\/Pulsante\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"_description canva-block canva-fs-xxsmall canva-lh-11 canva-fw-400\" style=\"color:var(--color-wp-block-subtitle);\">\n\t\t\t\t\tCrea un link\/pulsante tracciato come evento su GA\t\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"_css_classes canva-block canva-fs-xxsmall canva-lh-11 canva-fw-400\" style=\"color:var(--color-wp-block-subtitle);\">\n\t\t\t\t\tCSS Classes: mt-6\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\n\t\t<div class=\"_content canva-p-4\">\n\t\t\t\t\t\t\t<span class=\"canva-block canva-font-theme canva-fs-xsmall canva-lh-12\">\n\t\t\t\t\t<em>Fai click qui e poi sull&#8217;icona matita in alto per impostare il pulsante<\/em>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\n\t<\/div>\n\n\t<\/div>\n\n\n\n<div class=\"wp-block-column col-span-12 md:col-span-2 md:col-start-10 order-1 md:order-2 _tos tos-slide-u\"><figure id=\"media-71949\" class=\"wp-editor w-40\"   data-url=\"https:\/\/www.depureco.com\/wp-content\/uploads\/2023\/03\/icon-depureco-assistenza.svg\" data-size=\"x\" ><img decoding=\"auto\" class=\"_no-translate \" loading=\"lazy\" src=\"https:\/\/www.depureco.com\/wp-content\/uploads\/2023\/03\/icon-depureco-assistenza.svg\" srcset=\"https:\/\/www.depureco.com\/wp-content\/uploads\/2023\/03\/icon-depureco-assistenza.svg 640w, https:\/\/www.depureco.com\/wp-content\/uploads\/2023\/03\/icon-depureco-assistenza.svg 1280w, \" sizes=\"(max-width: 640px) 640px, 100vw\" alt=\"Icon Depureco Assistenza\" title=\"Icon Depureco Assistenza\" style=\"\" width=\"100%\" height=\"100%\"  fetchpriority=\"low\" \/> <figcaption class=\"image-caption block hidden\">Icon Depureco Assistenza<\/figcaption><\/figure><\/div>\n<\/div>\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n\n\n\n\t<div class=\"_canva-wp-block   _has-classes\" style=\"border: 1px dashed #1e88e5;\">\n\n\t\t\n\t<div class=\"_header\">\n\n\t\t<div class=\"_header-icon main-section-inner-blocks\">\n\t\t\t<div class=\"_header-icon-wrap canva-p-1\" style=\"background: var(--color-wp-block-bg-icon);\">\n\t\t\t\t<svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" x=\"0px\" y=\"0px\" viewbox=\"0 0 256 256\" style=\"enable-background:new 0 0 256 256;\" xml:space=\"preserve\" class=\"_icon icon-wp-block-main-section-inner-blocks \">\n<style type=\"text\/css\">\n\t.st1{fill:#FF0000;}\n\t.st2{fill:none;stroke:#000000;stroke-width:6;stroke-linecap:round;stroke-linejoin:round;stroke-miterlimit:10;}\n\t.st3{fill:none;stroke:#000000;stroke-width:6;stroke-miterlimit:10;}\n\t.st4{fill:none;stroke:#000000;stroke-width:12;stroke-miterlimit:10;}\n\t.st5{display:none;}\n\t.st6{display:inline;fill:#E6007E;}\n<\/style>\n<g id=\"Livello_1\" focusable=\"false\">\n\t<g>\n\t\t<rect x=\"60.5\" y=\"181.4\" style=\"fill:#1e88e5;\" width=\"20\" height=\"12\"><\/rect>\n\t\t<rect x=\"88.5\" y=\"65.4\" style=\"fill:#1e88e5;\" width=\"20\" height=\"12\"><\/rect>\n\t\t<rect x=\"57.5\" y=\"65.4\" style=\"fill:#1e88e5;\" width=\"20\" height=\"12\"><\/rect>\n\t\t<rect x=\"91.5\" y=\"181.4\" style=\"fill:#1e88e5;\" width=\"20\" height=\"12\"><\/rect>\n\t\t<rect x=\"24.5\" y=\"133.4\" style=\"fill:#1e88e5;\" width=\"12\" height=\"20\"><\/rect>\n\t\t<rect x=\"24.5\" y=\"102.4\" style=\"fill:#1e88e5;\" width=\"12\" height=\"20\"><\/rect>\n\t\t<path style=\"fill:#1e88e5;\" d=\"M36.5,77.4h10v-12h-10c-6.6,0-12,5.4-12,12v0c0,6.4,0,14,0,14h12V77.4z\"><\/path>\n\t\t<path style=\"fill:#1e88e5;\" d=\"M212.5,65.4v12h8v16h12V74c0-4.7-3.8-8.6-8.6-8.6H212.5z\"><\/path>\n\t\t<path style=\"fill:#1e88e5;\" d=\"M36.5,164.4h-12v17c0,6.6,5.4,12,12,12h13v-12h-13V164.4z\"><\/path>\n\t\t<rect x=\"119.5\" y=\"65.4\" style=\"fill:#1e88e5;\" width=\"20\" height=\"12\"><\/rect>\n\t\t<rect x=\"181.5\" y=\"65.4\" style=\"fill:#1e88e5;\" width=\"20\" height=\"12\"><\/rect>\n\t\t<rect x=\"220.5\" y=\"135.4\" style=\"fill:#1e88e5;\" width=\"12\" height=\"20\"><\/rect>\n\t\t<path style=\"fill:#1e88e5;\" d=\"M220.5,181.4h-9v12h12.4c4.7,0,8.6-3.8,8.6-8.6v0v-3.4v-15h-12V181.4z\"><\/path>\n\t\t<rect x=\"220.5\" y=\"104.4\" style=\"fill:#1e88e5;\" width=\"12\" height=\"20\"><\/rect>\n\t\t<rect x=\"122.5\" y=\"181.4\" style=\"fill:#1e88e5;\" width=\"20\" height=\"12\"><\/rect>\n\t\t<rect x=\"184.5\" y=\"181.4\" style=\"fill:#1e88e5;\" width=\"16\" height=\"12\"><\/rect>\n\t\t<rect x=\"150.5\" y=\"65.4\" style=\"fill:#1e88e5;\" width=\"20\" height=\"12\"><\/rect>\n\t\t<rect x=\"153.5\" y=\"181.4\" style=\"fill:#1e88e5;\" width=\"20\" height=\"12\"><\/rect>\n\t<\/g>\n\t<path d=\"M52.5,53.7V36h151v17.7h12V36c0-6.6-5.4-12-12-12h-151c-6.6,0-12,5.4-12,12v17.7H52.5z\"><\/path>\n\t<path d=\"M203.5,202.3V220h-151v-17.7h-12V220c0,6.6,5.4,12,12,12h151c6.6,0,12-5.4,12-12v-17.7H203.5z\"><\/path>\n<\/g>\n<g id=\"Note_e_spacer\" class=\"st5\">\n\t<rect class=\"st6\" width=\"24\" height=\"24\"><\/rect>\n\t<rect y=\"232\" class=\"st6\" width=\"24\" height=\"24\"><\/rect>\n<\/g>\n<\/svg>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t<div class=\"_header-info canva-flex-1\">\n\t\t\t<span class=\"_title canva-block canva-fs-xsmall canva-lh-12 canva-fw-700\" style=\"color:var(--color-wp-block-title);\">\n\t\t\t\tSezione Main\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"_description canva-block canva-fs-xxsmall canva-lh-11 canva-fw-400\" style=\"color:var(--color-wp-block-subtitle);\">\n\t\t\t\t\tContenitore di blocchi per sezione di pagina\t\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"_css_classes canva-block canva-fs-xxsmall canva-lh-11 canva-fw-400\" style=\"color:var(--color-wp-block-subtitle);\">\n\t\t\t\t\tCSS Classes: bg-black isdark py-24\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n        \n\t\t<div class=\"_content canva-p-4 canva-bg-white\">\n\n\t\t\t\n\t\t\t<div class=\"user-locked-inner-blocks\">\n\t\t\t\t\n\n<div class=\"wp-block-columns\">\n<div class=\"wp-block-column col-span-12 _tos tos-slide-r\">\n<h4 class=\"fs-h1 lh-11 wp-block-heading\">Cre\u0219tem prin<br><span class=\"text-selected\">Formare<\/span><\/h4>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns _gap-default items-center\">\n<div class=\"wp-block-column col-span-12 md:col-span-2 md:col-start-2 _tos tos-slide-u\"><figure id=\"media-71950\" class=\"wp-editor w-40\"   data-url=\"https:\/\/www.depureco.com\/wp-content\/uploads\/2023\/03\/icon-depureco-formazione.svg\" data-size=\"x\" ><img decoding=\"auto\" class=\"_no-translate \" loading=\"lazy\" src=\"https:\/\/www.depureco.com\/wp-content\/uploads\/2023\/03\/icon-depureco-formazione.svg\" srcset=\"https:\/\/www.depureco.com\/wp-content\/uploads\/2023\/03\/icon-depureco-formazione.svg 640w, https:\/\/www.depureco.com\/wp-content\/uploads\/2023\/03\/icon-depureco-formazione.svg 1280w, \" sizes=\"(max-width: 640px) 640px, 100vw\" alt=\"Icon Depureco Formazione\" title=\"Icon Depureco Formazione\" style=\"\" width=\"100%\" height=\"100%\"  fetchpriority=\"low\" \/> <figcaption class=\"image-caption block hidden\">Icon Depureco Formazione<\/figcaption><\/figure><\/div>\n\n\n\n<div class=\"wp-block-column col-span-12 md:col-span-8 md:col-start-5 _tos tos-slide-u\">\n<p>Oferim re\u021belei noastre de v\u00e2nz\u0103ri \u0219i partenerilor Depureco&nbsp;<strong>training-uri periodice<\/strong>, de actualizare \u0219i instruire cu privire la noile produse dezvoltate \u0219i la strategiile comerciale adoptate.<br>Cu ocazia&nbsp;<strong>lans\u0103rii de noi aspiratoare industriale<\/strong>&nbsp;organiz\u0103m, \u00een cadrul Depureco dar \u0219i la sediul distribuitorilor,&nbsp;<strong>parcursuri de formare<\/strong>&nbsp;destinate aprofund\u0103rii caracteristicilor \u0219i modului de func\u021bionare al echipamentelor.<\/p>\n\n\n\n\t<div class=\"_canva-wp-block\">\n\t\t\n\t<div class=\"_header\">\n\n\t\t<div class=\"_header-icon action-link\">\n\t\t\t<div class=\"_header-icon-wrap canva-p-1\" style=\"background: var(--color-wp-block-bg-icon);\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 512 512\" class=\"_icon link w-16\"><path d=\"M314.222 197.78c51.091 51.091 54.377 132.287 9.75 187.16-6.242 7.73-2.784 3.865-84.94 86.02-54.696 54.696-143.266 54.745-197.99 0-54.711-54.69-54.734-143.255 0-197.99 32.773-32.773 51.835-51.899 63.409-63.457 7.463-7.452 20.331-2.354 20.486 8.192a173.31 173.31 0 0 0 4.746 37.828c.966 4.029-.272 8.269-3.202 11.198L80.632 312.57c-32.755 32.775-32.887 85.892 0 118.8 32.775 32.755 85.892 32.887 118.8 0l75.19-75.2c32.718-32.725 32.777-86.013 0-118.79a83.722 83.722 0 0 0-22.814-16.229c-4.623-2.233-7.182-7.25-6.561-12.346 1.356-11.122 6.296-21.885 14.815-30.405l4.375-4.375c3.625-3.626 9.177-4.594 13.76-2.294 12.999 6.524 25.187 15.211 36.025 26.049zM470.958 41.04c-54.724-54.745-143.294-54.696-197.99 0-82.156 82.156-78.698 78.29-84.94 86.02-44.627 54.873-41.341 136.069 9.75 187.16 10.838 10.838 23.026 19.525 36.025 26.049 4.582 2.3 10.134 1.331 13.76-2.294l4.375-4.375c8.52-8.519 13.459-19.283 14.815-30.405.621-5.096-1.938-10.113-6.561-12.346a83.706 83.706 0 0 1-22.814-16.229c-32.777-32.777-32.718-86.065 0-118.79l75.19-75.2c32.908-32.887 86.025-32.755 118.8 0 32.887 32.908 32.755 86.025 0 118.8l-45.848 45.84c-2.93 2.929-4.168 7.169-3.202 11.198a173.31 173.31 0 0 1 4.746 37.828c.155 10.546 13.023 15.644 20.486 8.192 11.574-11.558 30.636-30.684 63.409-63.457 54.733-54.735 54.71-143.3-.001-197.991z\"><\/path><\/svg>\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t<div class=\"_header-info canva-flex-1\">\n\t\t\t<span class=\"_title canva-block canva-fs-xsmall canva-lh-12 canva-fw-700\" style=\"color:var(--color-wp-block-title);\">\n\t\t\t\tAction Link\/Pulsante\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"_description canva-block canva-fs-xxsmall canva-lh-11 canva-fw-400\" style=\"color:var(--color-wp-block-subtitle);\">\n\t\t\t\t\tCrea un link\/pulsante tracciato come evento su GA\t\t\t\t<\/span>\n\t\t\t\n\t\t\t\t\t\t\t<span class=\"_css_classes canva-block canva-fs-xxsmall canva-lh-11 canva-fw-400\" style=\"color:var(--color-wp-block-subtitle);\">\n\t\t\t\t\tCSS Classes: mt-6\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\n\t\t<div class=\"_content canva-p-4\">\n\t\t\t\t\t\t\t<span class=\"canva-block canva-font-theme canva-fs-xsmall canva-lh-12\">\n\t\t\t\t\t<em>Fai click qui e poi sull&#8217;icona matita in alto per impostare il pulsante<\/em>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\n\t<\/div>\n\n\t<\/div>\n<\/div>\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\n\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-69322","page","type-page","status-publish","hentry","optional-ro"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.8 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Servicii - Depureco<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.depureco.com\/ro\/servicii\/\" \/>\n<meta property=\"og:locale\" content=\"ro_RO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Servicii - Depureco\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.depureco.com\/ro\/servicii\/\" \/>\n<meta property=\"og:site_name\" content=\"Depureco\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/depurecoindustrialvacuums\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-27T13:46:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.depureco.com\/wp-content\/uploads\/2023\/03\/icon-depureco-dimostrazione.svg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Timp estimat pentru citire\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.depureco.com\\\/ro\\\/servicii\\\/\",\"url\":\"https:\\\/\\\/www.depureco.com\\\/ro\\\/servicii\\\/\",\"name\":\"Servicii - Depureco\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.depureco.com\\\/ro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.depureco.com\\\/ro\\\/servicii\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.depureco.com\\\/ro\\\/servicii\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.depureco.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/icon-depureco-dimostrazione.svg\",\"datePublished\":\"2023-02-24T15:15:10+00:00\",\"dateModified\":\"2023-03-27T13:46:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.depureco.com\\\/ro\\\/servicii\\\/#breadcrumb\"},\"inLanguage\":\"ro-RO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.depureco.com\\\/ro\\\/servicii\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/www.depureco.com\\\/ro\\\/servicii\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.depureco.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/icon-depureco-dimostrazione.svg\",\"contentUrl\":\"https:\\\/\\\/www.depureco.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/icon-depureco-dimostrazione.svg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.depureco.com\\\/ro\\\/servicii\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.depureco.com\\\/ro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Servicii\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.depureco.com\\\/ro\\\/#website\",\"url\":\"https:\\\/\\\/www.depureco.com\\\/ro\\\/\",\"name\":\"Depureco\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.depureco.com\\\/ro\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.depureco.com\\\/ro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ro-RO\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.depureco.com\\\/ro\\\/#organization\",\"name\":\"Depureco Industrial Vacuums Srl\",\"alternateName\":\"Depureco\",\"url\":\"https:\\\/\\\/www.depureco.com\\\/ro\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ro-RO\",\"@id\":\"https:\\\/\\\/www.depureco.com\\\/ro\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.depureco.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/depureco-logo-colors.svg\",\"contentUrl\":\"https:\\\/\\\/www.depureco.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/depureco-logo-colors.svg\",\"width\":1,\"height\":1,\"caption\":\"Depureco Industrial Vacuums Srl\"},\"image\":{\"@id\":\"https:\\\/\\\/www.depureco.com\\\/ro\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/depurecoindustrialvacuums\\\/\",\"https:\\\/\\\/it.linkedin.com\\\/company\\\/depureco-industrial-vacuums\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/DEPURECOsrl\\\/feed\\\/\",\"https:\\\/\\\/www.wikidata.org\\\/wiki\\\/Q136332161\"],\"description\":\"Depureco is a leading manufacturer of Italian-engineered industrial vacuum systems known for rugged build quality, long-life components, and high filtration performance\u2014including HEPA\\\/H14 and ATEX options. Our engineering team delivers expert customization, tailoring units, accessories, and central systems to each application for safer, cleaner, and more efficient operations.\",\"email\":\"depureco@depureco.com\",\"telephone\":\"+39 011 98.59.117\",\"legalName\":\"Depureco Industrial Vacuums Srl\",\"foundingDate\":\"1972-01-01\",\"vatID\":\"IT02258610357\",\"taxID\":\"IT02258610357\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"51\",\"maxValue\":\"200\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Servicii - Depureco","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.depureco.com\/ro\/servicii\/","og_locale":"ro_RO","og_type":"article","og_title":"Servicii - Depureco","og_url":"https:\/\/www.depureco.com\/ro\/servicii\/","og_site_name":"Depureco","article_publisher":"https:\/\/www.facebook.com\/depurecoindustrialvacuums\/","article_modified_time":"2023-03-27T13:46:49+00:00","og_image":[{"url":"https:\/\/www.depureco.com\/wp-content\/uploads\/2023\/03\/icon-depureco-dimostrazione.svg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Timp estimat pentru citire":"2 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.depureco.com\/ro\/servicii\/","url":"https:\/\/www.depureco.com\/ro\/servicii\/","name":"Servicii - Depureco","isPartOf":{"@id":"https:\/\/www.depureco.com\/ro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.depureco.com\/ro\/servicii\/#primaryimage"},"image":{"@id":"https:\/\/www.depureco.com\/ro\/servicii\/#primaryimage"},"thumbnailUrl":"https:\/\/www.depureco.com\/wp-content\/uploads\/2023\/03\/icon-depureco-dimostrazione.svg","datePublished":"2023-02-24T15:15:10+00:00","dateModified":"2023-03-27T13:46:49+00:00","breadcrumb":{"@id":"https:\/\/www.depureco.com\/ro\/servicii\/#breadcrumb"},"inLanguage":"ro-RO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.depureco.com\/ro\/servicii\/"]}]},{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/www.depureco.com\/ro\/servicii\/#primaryimage","url":"https:\/\/www.depureco.com\/wp-content\/uploads\/2023\/03\/icon-depureco-dimostrazione.svg","contentUrl":"https:\/\/www.depureco.com\/wp-content\/uploads\/2023\/03\/icon-depureco-dimostrazione.svg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.depureco.com\/ro\/servicii\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.depureco.com\/ro\/"},{"@type":"ListItem","position":2,"name":"Servicii"}]},{"@type":"WebSite","@id":"https:\/\/www.depureco.com\/ro\/#website","url":"https:\/\/www.depureco.com\/ro\/","name":"Depureco","description":"","publisher":{"@id":"https:\/\/www.depureco.com\/ro\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.depureco.com\/ro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ro-RO"},{"@type":"Organization","@id":"https:\/\/www.depureco.com\/ro\/#organization","name":"Depureco Industrial Vacuums Srl","alternateName":"Depureco","url":"https:\/\/www.depureco.com\/ro\/","logo":{"@type":"ImageObject","inLanguage":"ro-RO","@id":"https:\/\/www.depureco.com\/ro\/#\/schema\/logo\/image\/","url":"https:\/\/www.depureco.com\/wp-content\/uploads\/2023\/03\/depureco-logo-colors.svg","contentUrl":"https:\/\/www.depureco.com\/wp-content\/uploads\/2023\/03\/depureco-logo-colors.svg","width":1,"height":1,"caption":"Depureco Industrial Vacuums Srl"},"image":{"@id":"https:\/\/www.depureco.com\/ro\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/depurecoindustrialvacuums\/","https:\/\/it.linkedin.com\/company\/depureco-industrial-vacuums","https:\/\/www.youtube.com\/user\/DEPURECOsrl\/feed\/","https:\/\/www.wikidata.org\/wiki\/Q136332161"],"description":"Depureco is a leading manufacturer of Italian-engineered industrial vacuum systems known for rugged build quality, long-life components, and high filtration performance\u2014including HEPA\/H14 and ATEX options. Our engineering team delivers expert customization, tailoring units, accessories, and central systems to each application for safer, cleaner, and more efficient operations.","email":"depureco@depureco.com","telephone":"+39 011 98.59.117","legalName":"Depureco Industrial Vacuums Srl","foundingDate":"1972-01-01","vatID":"IT02258610357","taxID":"IT02258610357","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"51","maxValue":"200"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.depureco.com\/ro\/wp-json\/wp\/v2\/pages\/69322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.depureco.com\/ro\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.depureco.com\/ro\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.depureco.com\/ro\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.depureco.com\/ro\/wp-json\/wp\/v2\/comments?post=69322"}],"version-history":[{"count":0,"href":"https:\/\/www.depureco.com\/ro\/wp-json\/wp\/v2\/pages\/69322\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.depureco.com\/ro\/wp-json\/wp\/v2\/media?parent=69322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}